{"id":6434,"date":"2022-07-28T14:51:36","date_gmt":"2022-07-28T18:51:36","guid":{"rendered":"https:\/\/www.seochc.on.ca\/?page_id=6434"},"modified":"2024-10-28T10:37:25","modified_gmt":"2024-10-28T14:37:25","slug":"seochc-accountability","status":"publish","type":"page","link":"https:\/\/www.seochc.on.ca\/fr\/about-us\/seochc-accountability\/","title":{"rendered":"Responsabilit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6434\" class=\"elementor elementor-6434\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82c3cb7 pull-up-title elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82c3cb7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3103aff\" data-id=\"3103aff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b00fc9a elementor-widget elementor-widget-heading\" data-id=\"b00fc9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Accountability<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4acd02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4acd02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8261a30\" data-id=\"8261a30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3798a1a tpg-filter-type-button filter-preloader-on title_position_default title_hover_border_default title-default img_hover_animation_default readmore-btn-default-style grid-hover-overlay-type-always tpg-el-box-border-enable tpg-border-bottom-disable elementor-widget elementor-widget-tpg-grid-layout\" data-id=\"3798a1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tpg-grid-layout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"rt-container-fluid rt-tpg-container tpg-el-main-wrapper clearfix grid-layout3-main \"\n\t\t\t id=\"rt-tpg-container-3223392525\"\n\t\t\t data-layout=\"grid-layout3\"\n\t\t\t data-grid-style=\"tpg-full-height\"\n\t\t\t data-sc-id=\"elementor\"\n\t\t\t data-el-settings='{&quot;block_type&quot;:&quot;elementor&quot;,&quot;is_gutenberg&quot;:&quot;&quot;,&quot;prefix&quot;:&quot;grid&quot;,&quot;grid_column&quot;:&quot;0&quot;,&quot;grid_column_tablet&quot;:&quot;0&quot;,&quot;grid_column_mobile&quot;:&quot;0&quot;,&quot;layout&quot;:&quot;grid-layout3&quot;,&quot;pagination_type&quot;:&quot;pagination&quot;,&quot;total_pages&quot;:0,&quot;posts_per_page&quot;:-1,&quot;layout_style&quot;:&quot;tpg-full-height&quot;,&quot;show_title&quot;:&quot;show&quot;,&quot;current_query&quot;:&quot;&quot;,&quot;excerpt_type&quot;:&quot;character&quot;,&quot;excerpt_limit&quot;:200,&quot;excerpt_more_text&quot;:&quot;...&quot;,&quot;title_limit&quot;:&quot;&quot;,&quot;title_limit_type&quot;:&quot;word&quot;,&quot;title_visibility_style&quot;:&quot;default&quot;,&quot;post_link_type&quot;:&quot;default&quot;,&quot;link_target&quot;:&quot;_self&quot;,&quot;hover_animation&quot;:&quot;default&quot;,&quot;show_thumb&quot;:&quot;show&quot;,&quot;show_meta&quot;:&quot;&quot;,&quot;show_author&quot;:&quot;show&quot;,&quot;show_author_image&quot;:&quot;icon&quot;,&quot;author_icon_visibility&quot;:&quot;show&quot;,&quot;show_meta_icon&quot;:&quot;yes&quot;,&quot;show_category&quot;:&quot;show&quot;,&quot;show_date&quot;:&quot;show&quot;,&quot;show_tags&quot;:false,&quot;show_comment_count&quot;:false,&quot;show_comment_count_label&quot;:&quot;yes&quot;,&quot;comment_count_label_singular&quot;:&quot;Comment&quot;,&quot;comment_count_label_plural&quot;:&quot;Comments&quot;,&quot;show_post_count&quot;:false,&quot;post_count_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;show_excerpt&quot;:&quot;&quot;,&quot;show_read_more&quot;:&quot;show&quot;,&quot;show_btn_icon&quot;:false,&quot;show_social_share&quot;:&quot;default&quot;,&quot;show_cat_icon&quot;:false,&quot;is_thumb_linked&quot;:&quot;yes&quot;,&quot;media_source&quot;:&quot;feature_image&quot;,&quot;no_posts_found_text&quot;:&quot;No posts found.&quot;,&quot;image_size&quot;:&quot;medium_large&quot;,&quot;image_offset&quot;:&quot;medium_large&quot;,&quot;is_default_img&quot;:false,&quot;default_image&quot;:{&quot;url&quot;:&quot;https:\/\/www.seochc.on.ca\/wp-content\/plugins\/the-post-grid\/assets\/images\/placeholder.jpg&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;thumb_overlay_visibility&quot;:&quot;&quot;,&quot;overlay_type&quot;:&quot;&quot;,&quot;title_tag&quot;:&quot;h2&quot;,&quot;post_type&quot;:&quot;wpdmpro&quot;,&quot;meta_separator&quot;:&quot;default&quot;,&quot;readmore_icon_position&quot;:&quot;right&quot;,&quot;read_more_label&quot;:&quot;Read More&quot;,&quot;readmore_btn_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;category_position&quot;:&quot;default&quot;,&quot;title_position&quot;:&quot;default&quot;,&quot;category_style&quot;:&quot;style1&quot;,&quot;is_thumb_lightbox&quot;:&quot;default&quot;,&quot;author_prefix&quot;:&quot;By&quot;,&quot;cat_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;tag_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;date_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;user_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;date_archive_link&quot;:&quot;yes&quot;,&quot;meta_ordering&quot;:[{&quot;meta_title&quot;:&quot;Author&quot;,&quot;meta_name&quot;:&quot;author&quot;,&quot;_id&quot;:&quot;22133ca&quot;,&quot;repeater_hidden&quot;:&quot;&quot;},{&quot;meta_title&quot;:&quot;Date&quot;,&quot;meta_name&quot;:&quot;date&quot;,&quot;_id&quot;:&quot;5c2eae9&quot;,&quot;repeater_hidden&quot;:&quot;&quot;},{&quot;meta_title&quot;:&quot;Category&quot;,&quot;meta_name&quot;:&quot;category&quot;,&quot;_id&quot;:&quot;8a0345e&quot;,&quot;repeater_hidden&quot;:&quot;&quot;},{&quot;meta_title&quot;:&quot;Tags&quot;,&quot;meta_name&quot;:&quot;tags&quot;,&quot;_id&quot;:&quot;85096aa&quot;,&quot;repeater_hidden&quot;:&quot;&quot;},{&quot;meta_title&quot;:&quot;Comment Count&quot;,&quot;meta_name&quot;:&quot;comment_count&quot;,&quot;_id&quot;:&quot;84427d1&quot;,&quot;repeater_hidden&quot;:&quot;&quot;},{&quot;meta_title&quot;:&quot;Post Count&quot;,&quot;meta_name&quot;:&quot;post_count&quot;,&quot;_id&quot;:&quot;48aa6a9&quot;,&quot;repeater_hidden&quot;:&quot;&quot;},{&quot;meta_title&quot;:&quot;Post Like&quot;,&quot;meta_name&quot;:&quot;post_like&quot;,&quot;_id&quot;:&quot;d1ca2c3&quot;,&quot;repeater_hidden&quot;:&quot;&quot;}],&quot;comment_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;image_custom_dimension&quot;:[],&quot;img_crop_style&quot;:&quot;&quot;,&quot;show_acf&quot;:&quot;&quot;,&quot;search_by&quot;:&quot;all_content&quot;,&quot;multiple_taxonomy&quot;:false,&quot;multi_tax_relation&quot;:&quot;OR&quot;,&quot;tax_filter_search&quot;:false,&quot;tax_filter_clear_btn&quot;:false,&quot;show_event_date&quot;:false,&quot;start_date_label&quot;:&quot;Start Date:&quot;,&quot;end_date_label&quot;:&quot;End Date:&quot;,&quot;event_title&quot;:&quot;Event Information:&quot;,&quot;event_date_format&quot;:&quot;F j, Y g:i a&quot;,&quot;custom_event_date_format&quot;:&quot;&quot;,&quot;wpdmpro_taxonomy&quot;:&quot;wpdmcategory&quot;,&quot;wpdmpro_tags&quot;:&quot;wpdmtag&quot;}'\n\t\t\t data-el-query='{&quot;post_type&quot;:&quot;wpdmpro&quot;,&quot;post_status&quot;:&quot;publish&quot;,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;DESC&quot;,&quot;tax_query&quot;:{&quot;0&quot;:{&quot;taxonomy&quot;:&quot;wpdmcategory&quot;,&quot;field&quot;:&quot;term_id&quot;,&quot;terms&quot;:[&quot;63&quot;,&quot;71&quot;,&quot;72&quot;,&quot;73&quot;,&quot;121&quot;]},&quot;relation&quot;:&quot;OR&quot;},&quot;posts_per_page&quot;:-1}'\n\t\t\t data-el-path='\/home\/seochc\/public_html\/wp-content\/plugins\/the-post-grid\/templates\/elementor\/'\n\t\t>\n\t\t\t\t\t\t<div class='tpg-header-wrapper '>\n\t\t\t\t<div class='rt-layout-filter-container rt-clear filter-clear-disable'><div class='rt-filter-wrap'><div class='filter-left-wrapper '><div class='rt-filter-item-wrap rt-tax-filter rt-filter-button-wrap ' data-taxonomy='wpdmcategory' data-filter='taxonomy'><span class='term-button-item rt-filter-button-item  ' data-term='71'>Annual Reports<\/span><span class='term-button-item rt-filter-button-item  ' data-term='72'>Financial Statements<\/span><span class='term-button-item rt-filter-button-item  ' data-term='73'>Midwifery Program<\/span><span class='term-button-item rt-filter-button-item  ' data-term='63'>Miscellaneous<\/span><span class='term-button-item rt-filter-button-item  ' data-term='121'>Quality Improvement<\/span><\/div><\/div><\/div><\/div>\t\t\t<\/div>\n\n\t\t\t<div data-title=\"Loading ...\" class=\"rt-row rt-content-loader grid-layout3 grid-behaviour tpg-full-height grid_layout_wrapper\">\n\t\t\t\t\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"9445\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"9445\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2024-2025\/\" class=\"tpg-post-link\" target=\"_self\">                        <img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2025\/09\/thumbnail_annual-report_2024-2025_FR-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"thumbnail for french version of 2024 - 2025 annual report\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"9445\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2024-2025\/\" class=\"tpg-post-link\" target=\"_self\">Rapport Annuel 2024-2025<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"9445\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2024-2025\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"9439\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"9439\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2024-2025\/\" class=\"tpg-post-link\" target=\"_self\">                        <img decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2025\/09\/thumbnail_annual-report_2024-2025_EN-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"thumbnail for annual report 2024 - 2025\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"9439\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2024-2025\/\" class=\"tpg-post-link\" target=\"_self\">Annual Report 2024-2025<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"9439\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2024-2025\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"9358\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"9358\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2024-25\/\" class=\"tpg-post-link\" target=\"_self\">                        <img decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2025\/08\/thumbnail_financial-statements-midwifery-2024-25-768x403.jpeg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"cover image for midwifery financial statements\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"9358\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2024-25\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for Midwifery Program 2024-25<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"9358\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2024-25\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"9356\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"9356\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2024-25\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2025\/08\/thumbnail_financial-statements-2024-25-768x403.jpeg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"cover image for 2025 financial statements document\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"9356\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2024-25\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for 2024-25<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"9356\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2024-25\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"8555\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"8555\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2022-2\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2024\/08\/thumbnail_financial-statements-2023-1-768x403.png\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Financial Statements for 2023\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"8555\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2022-2\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for 2023<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"8555\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2022-2\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"8554\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"8554\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2022\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2023\/07\/thumbnail_financial-statements-2022-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"cover page for financial statements for 2022\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"8554\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2022\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for 2022<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"8554\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2022\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"8547\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"8547\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2022-2\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2024\/08\/thumbnail_financial-statements-midwifery-2023-1-768x403.png\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Financial Statements for Midwifery Program 2023\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"8547\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2022-2\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for Midwifery Program 2023<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"8547\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2022-2\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"8536\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"8536\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2023-2024\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2024\/08\/template_annual-reports-thumbnailArtboard-2-768x403.png\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Annual Report 2023-2024\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"8536\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2023-2024\/\" class=\"tpg-post-link\" target=\"_self\">Annual Report 2023-2024<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"8536\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2023-2024\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"8531\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"8531\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2023-2024\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2024\/08\/template_annual-reports-thumbnailArtboard-1-768x403.png\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Rapport Annuel 2023-2024\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"8531\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2023-2024\/\" class=\"tpg-post-link\" target=\"_self\">Rapport Annuel 2023-2024<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"8531\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2023-2024\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"7865\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"7865\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/quality-improvement-narrative-2023-2024\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2023\/09\/4.-c.-SEOCHC-HQO-QIP-Narrative-2023-24-1-pdf.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"593\"\n                             alt=\"Quality Improvement Narrative 2023-2024\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"7865\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/quality-improvement-narrative-2023-2024\/\" class=\"tpg-post-link\" target=\"_self\">Quality Improvement Narrative 2023-2024<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"7865\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/quality-improvement-narrative-2023-2024\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"7862\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"7862\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/quality-improvement-2023-2024\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2023\/09\/4.-c.-SEOCHC-HQO-QIP-Workplan-2023-24-1-pdf.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"593\"\n                             alt=\"Quality Improvement 2023-2024\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"7862\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/quality-improvement-2023-2024\/\" class=\"tpg-post-link\" target=\"_self\">Quality Improvement 2023-2024<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"7862\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/quality-improvement-2023-2024\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"7846\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"7846\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2022-2023\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2021\/02\/thumbnail_annual-report_2022-2023_FR-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"rapport annuel 2022-2023\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"7846\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2022-2023\/\" class=\"tpg-post-link\" target=\"_self\">Rapport Annuel 2022-2023<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"7846\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2022-2023\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"7845\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"7845\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2022-2023\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2021\/02\/thumbnail_annual-report_2022-2023_EN-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"annual report 2022-2023\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"7845\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2022-2023\" class=\"tpg-post-link\" target=\"_self\">Annual Report 2022-2023<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"7845\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2022-2023\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"7708\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"7708\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2022\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2023\/07\/thumbnail_financial-statements-midwifery-2022-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"cover page for midwifery financial statements for 2022\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"7708\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2022\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for Midwifery Program 2022<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"7708\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2022\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"7555\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"7555\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/multi-sector-service-accountability-agreement\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2023\/05\/SEOCHC_2023-24_MSAA_Signed-by-OH-East-pdf.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"994\"\n                             alt=\"Multi-Sector Service Accountability Agreement\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"7555\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/multi-sector-service-accountability-agreement\/\" class=\"tpg-post-link\" target=\"_self\">Multi-Sector Service Accountability Agreement<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"7555\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/multi-sector-service-accountability-agreement\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6654\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6654\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2021-2022\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/08\/thumbnail_annual-report_2021-2022_FR-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"annual report 2021-2022 in french\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6654\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2021-2022\/\" class=\"tpg-post-link\" target=\"_self\">Rapport Annuel 2021-2022<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6654\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2021-2022\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6639\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6639\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2021-2022\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/08\/thumbnail_annual-report_2021-2022_EN-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"annual report 2021-2022 in english\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6639\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2021-2022\/\" class=\"tpg-post-link\" target=\"_self\">Annual Report 2021-2022<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6639\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2021-2022\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6511\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6511\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2021\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/thumbnail_financial-statements-2021-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"financial statements 2021\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6511\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2021\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for 2021<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6511\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2021\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6509\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6509\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2021\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/thumbnail_financial-statements-midwifery-2021-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"midwifery program financial statements 2021\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6509\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2021\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for Midwifery Program 2021<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6509\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2021\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6508\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6508\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2020\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/thumbnail_financial-statements-2020-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"financial statements 2020\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6508\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2020\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for 2020<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6508\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2020\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6504\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6504\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2020\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/thumbnail_financial-statements-midwifery-2020-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Financial Statements for Midwifery Program 2020\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6504\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2020\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for Midwifery Program 2020<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6504\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-midwifery-program-2020\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6502\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6502\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2019\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/thumbnail_financial-statements-2019-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"financial statements 2019\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6502\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2019\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for 2019<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6502\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2019\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6500\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6500\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2018\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/thumbnail_financial-statements-2018-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"financial statements 2018\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6500\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2018\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for 2018<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6500\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2018\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6498\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6498\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2017\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/thumbnail_financial-statements-2017-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"financial statements 2017\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6498\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2017\/\" class=\"tpg-post-link\" target=\"_self\">Financial Statements for 2017<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6498\" href=\"https:\/\/www.seochc.on.ca\/fr\/download\/financial-statements-for-2017\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6433\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6433\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2020-2021\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2021\/02\/thumbnail_annual-report_2020-2021_FR-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Rapport annuel 2020-2021\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6433\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2020-2021\/\" class=\"tpg-post-link\" target=\"_self\">Rapport annuel 2020-2021<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6433\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2020-2021\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6432\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6432\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2020-2021\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2021\/02\/thumbnail_annual-report_2020-2021_EN-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Annual Report 2020-2021 (EN)\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6432\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2020-2021\/\" class=\"tpg-post-link\" target=\"_self\">Annual Report 2020-2021<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6432\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2020-2021\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6430\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6430\" href=\"https:\/\/south-east-ottawa.cscottawachc.org\/index-fr.html\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/thumbnail_annual-report_2019-2020_FR-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"rapport annuel 2019-2020\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6430\" href=\"https:\/\/south-east-ottawa.cscottawachc.org\/index-fr.html\" class=\"tpg-post-link\" target=\"_self\">Rapport annuel 2019-2020<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6430\" href=\"https:\/\/south-east-ottawa.cscottawachc.org\/index-fr.html\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6428\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6428\" href=\"https:\/\/south-east-ottawa.cscottawachc.org\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/thumbnail_annual-report_2019-2020_EN-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"annual report 2019-2020\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6428\" href=\"https:\/\/south-east-ottawa.cscottawachc.org\/\" class=\"tpg-post-link\" target=\"_self\">Annual Report 2019-2020<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6428\" href=\"https:\/\/south-east-ottawa.cscottawachc.org\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6427\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6427\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2018-2019\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2021\/02\/thumbnail_annual-report_2018-2019_FR-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Annual Report 2018-2019 (FR)\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6427\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2018-2019\/\" class=\"tpg-post-link\" target=\"_self\">Rapport annuel 2018-2019<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6427\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2018-2019\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6426\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6426\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2018-2019\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2021\/02\/thumbnail_annual-report_2018-2019_EN-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Annual Report 2018-2019 (EN)\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6426\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2018-2019\/\" class=\"tpg-post-link\" target=\"_self\">Annual Report 2018-2019<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6426\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2018-2019\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6425\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6425\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2017-2018\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2021\/02\/thumbnail_annual-report_2017-2018_FR-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Annual Report 2017-2018 (FR)\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6425\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2017-2018\/\" class=\"tpg-post-link\" target=\"_self\">Rapport annuel 2017-2018<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6425\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2017-2018\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6424\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6424\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2017-2018\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2021\/02\/thumbnail_annual-report_2017-2018_EN-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Annual Report 2017-2018 (EN)\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6424\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2017-2018\/\" class=\"tpg-post-link\" target=\"_self\">Annual Report 2017-2018<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6424\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2017-2018\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6423\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6423\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2016-2017\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2021\/02\/thumbnail_annual-report_2016-2017_FR-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Rapport annuel 2016-2017\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6423\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2016-2017\/\" class=\"tpg-post-link\" target=\"_self\">Rapport annuel 2016-2017<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6423\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/rapport-annuel-2016-2017\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"rt-col-md-4 rt-col-sm-6 rt-col-xs-12 default rt-grid-item\" data-id=\"6422\">\n\t<div class=\"rt-holder tpg-post-holder \">\n\t\t<div class=\"rt-detail rt-el-content-wrapper\">\n\t\t\t\t\t\t\t<div class=\"rt-img-holder tpg-el-image-wrap has-thumbnail\">\n\t\t\t\t\t<a data-id=\"6422\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2016-2017\/\" class=\"tpg-post-link\" target=\"_self\">                        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2021\/02\/thumbnail_annual-report_2016-2017_EN-768x403.jpg\"\n                             class=\"rt-img-responsive\"\n                             width=\"768\"\n                             height=\"403\"\n                             alt=\"Annual Report 2016-2017 (EN)\">\n                        \n                            \n        <\/a>\n                <div class=\"overlay grid-hover-content\"><\/div>\n        \t\t\t\t<\/div>\n\t\t\t\n\n\t\t\t<div class=\"entry-title-wrapper\"><h2 class=\"entry-title\"><a data-id=\"6422\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2016-2017\/\" class=\"tpg-post-link\" target=\"_self\">Annual Report 2016-2017<\/a><\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t        <div class=\"post-footer\">\n            <div class=\"post-footer\">\n                <div class=\"read-more\">\n                    <a data-id=\"6422\" href=\"https:\/\/www.seochc.on.ca\/about-us\/seochc-accountability\/annual-report-2016-2017\/\" class=\"tpg-post-link\" target=\"_self\">Read More<\/a>                <\/div>\n            <\/div>\n        <\/div>\n        \t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Accountability Annual ReportsFinancial StatementsMidwifery ProgramMiscellaneousQuality Improvement Financial Statements for 2023 Read More Financial Statements for 2022 Read More Financial Statements for Midwifery Program 2023 Read More Annual Report 2023-2024 Read More Rapport Annuel 2023-2024 Read More Quality Improvement Narrative 2023-2024 Read More Quality Improvement 2023-2024 Read More Rapport Annuel 2022-2023 Read More Annual Report 2022-2023 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6435,"parent":4607,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-6434","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"rttpg_featured_image_url":{"full":["https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/seochc-reporting_fimage.jpg",1200,630,false],"landscape":["https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/seochc-reporting_fimage.jpg",1200,630,false],"portraits":["https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/seochc-reporting_fimage.jpg",1200,630,false],"thumbnail":["https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/seochc-reporting_fimage-150x150.jpg",150,150,true],"medium":["https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/seochc-reporting_fimage-300x158.jpg",300,158,true],"large":["https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/seochc-reporting_fimage-1024x538.jpg",1024,538,true],"1536x1536":["https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/seochc-reporting_fimage.jpg",1200,630,false],"2048x2048":["https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/seochc-reporting_fimage.jpg",1200,630,false],"trp-custom-language-flag":["https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/seochc-reporting_fimage.jpg",18,9,false],"rt_custom":["https:\/\/www.seochc.on.ca\/wp-content\/uploads\/2022\/07\/seochc-reporting_fimage.jpg",1200,630,false]},"rttpg_author":{"display_name":"mastercontroller","author_link":"https:\/\/www.seochc.on.ca\/fr\/author\/mastercontroller\/"},"rttpg_comment":0,"rttpg_category":null,"rttpg_excerpt":"Accountability Annual ReportsFinancial StatementsMidwifery ProgramMiscellaneousQuality Improvement Financial Statements for 2023 Read More Financial Statements for 2022 Read More Financial Statements for Midwifery Program 2023 Read More Annual Report 2023-2024 Read More Rapport Annuel 2023-2024 Read More Quality Improvement Narrative 2023-2024 Read More Quality Improvement 2023-2024 Read More Rapport Annuel 2022-2023 Read More Annual Report 2022-2023&hellip;","_links":{"self":[{"href":"https:\/\/www.seochc.on.ca\/fr\/wp-json\/wp\/v2\/pages\/6434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seochc.on.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.seochc.on.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.seochc.on.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seochc.on.ca\/fr\/wp-json\/wp\/v2\/comments?post=6434"}],"version-history":[{"count":38,"href":"https:\/\/www.seochc.on.ca\/fr\/wp-json\/wp\/v2\/pages\/6434\/revisions"}],"predecessor-version":[{"id":8705,"href":"https:\/\/www.seochc.on.ca\/fr\/wp-json\/wp\/v2\/pages\/6434\/revisions\/8705"}],"up":[{"embeddable":true,"href":"https:\/\/www.seochc.on.ca\/fr\/wp-json\/wp\/v2\/pages\/4607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seochc.on.ca\/fr\/wp-json\/wp\/v2\/media\/6435"}],"wp:attachment":[{"href":"https:\/\/www.seochc.on.ca\/fr\/wp-json\/wp\/v2\/media?parent=6434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}